{"id":5772,"date":"2022-10-02T00:38:22","date_gmt":"2022-10-01T22:38:22","guid":{"rendered":"https:\/\/www.official-trailer.com\/espanol\/?p=5772"},"modified":"2022-10-02T00:38:22","modified_gmt":"2022-10-01T22:38:22","slug":"carrie","status":"publish","type":"post","link":"https:\/\/www.official-trailer.com\/espanol\/carrie\/","title":{"rendered":"Carrie"},"content":{"rendered":"<p><\/p>\n<p>Carrie White, una adolescente a la que sus compa\u00f1eros humillan constantemente, posee poderes ps\u00edquicos que se manifiestan cuando se siente dominada por la ira. El d\u00eda del baile de graduaci\u00f3n la situaci\u00f3n llega a hac\u00e9rsele insoportable.<\/p>\n<p>Stars: [<a href=\"https:\/\/www.official-trailer.com\/espanol\/?s=Chlo\u00eb+Grace+Moretz\">Chlo\u00eb Grace Moretz<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/espanol\/?s=Julianne+Moore\">Julianne Moore<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/espanol\/?s=Gabriella+Wilde\">Gabriella Wilde<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/espanol\/?s=Judy+Greer\">Judy Greer<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/espanol\/?s=Portia+Doubleday\">Portia Doubleday<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/espanol\/?s=Ansel+Elgort\">Ansel Elgort<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/espanol\/?s=Alex+Russell\">Alex Russell<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/espanol\/?s=Zo\u00eb+Belkin\">Zo\u00eb Belkin<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/espanol\/?s=Samantha+Weinstein\">Samantha Weinstein<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/espanol\/?s=Karissa+Strain\">Karissa Strain<\/a>]","protected":false},"excerpt":{"rendered":"<p>Carrie White, una adolescente a la que sus compa\u00f1eros humillan constantemente, posee poderes ps\u00edquicos que se manifiestan cuando se siente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,12],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.official-trailer.com\/espanol\/wp-json\/wp\/v2\/posts\/5772"}],"collection":[{"href":"https:\/\/www.official-trailer.com\/espanol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.official-trailer.com\/espanol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.official-trailer.com\/espanol\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.official-trailer.com\/espanol\/wp-json\/wp\/v2\/comments?post=5772"}],"version-history":[{"count":0,"href":"https:\/\/www.official-trailer.com\/espanol\/wp-json\/wp\/v2\/posts\/5772\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.official-trailer.com\/espanol\/wp-json\/wp\/v2\/media?parent=5772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.official-trailer.com\/espanol\/wp-json\/wp\/v2\/categories?post=5772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.official-trailer.com\/espanol\/wp-json\/wp\/v2\/tags?post=5772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}