{"id":2869,"date":"2020-06-26T16:48:59","date_gmt":"2020-06-26T14:48:59","guid":{"rendered":"https:\/\/www.official-trailer.de\/?p=2869"},"modified":"2020-06-26T16:48:59","modified_gmt":"2020-06-26T14:48:59","slug":"huhn-mit-pflaumen","status":"publish","type":"post","link":"https:\/\/www.official-trailer.com\/deutsch\/huhn-mit-pflaumen\/","title":{"rendered":"Huhn mit Pflaumen"},"content":{"rendered":"<p><\/p>\n<p>Huhn mit Pflaumen f\u00fchrt uns in das Teheran der F\u00fcnfziger Jahre: Der Violinenvirtuose Nasser-Ali Khan hat ein gebrochenes Herz \u2013 seit sein Instrument bei einem Streit entzwei ging, ist seine Musik ohne Seele. Das Instrument ist das Symbol der unerf\u00fcllten Liebe zwischen Nasser-Ali und der wundersch\u00f6nen Ir\u00e2ne. Ihr Vater stand einer Heirat im Wege und so musste sich Nasser-Ali f\u00fcr immer von seiner geliebten Ir\u00e2ne trennen. Doch seine Liebe erf\u00fcllte sich im Spiel auf der Violine, die ihm sein Lehrer nach der schmerzvollen Trennung geschenkt hatte. All seine Sehnsucht legte Nasser-Ali in die Musik und wurde so zu einem einzigartigen Virtuosen. Mit dem Verlust der Violine hat Nasser-Ali auch der Lebensmut verlassen. Er begibt sich auf die Suche nach einem Ersatz und taucht in Erinnerungen an seine Vergangenheit ein.<\/p>\n<p>Stars: [<a href=\"https:\/\/www.official-trailer.com\/deutsch\/?s=Mathieu+Amalric\">Mathieu Amalric<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/deutsch\/?s=Edouard+Baer\">Edouard Baer<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/deutsch\/?s=Maria+de+Medeiros\">Maria de Medeiros<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/deutsch\/?s=Golshifte+Farahani\">Golshifte Farahani<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/deutsch\/?s=Chiara+Mastroianni\">Chiara Mastroianni<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/deutsch\/?s=Mathis+Bour\">Mathis Bour<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/deutsch\/?s=Enna+Balland\">Enna Balland<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/deutsch\/?s=Didier+Flamand\">Didier Flamand<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/deutsch\/?s=Serge+Ave\u0301dikian\">Serge Ave\u0301dikian<\/a>\/<a href=\"https:\/\/www.official-trailer.com\/deutsch\/?s=Rona+Hartner\">Rona Hartner<\/a>]","protected":false},"excerpt":{"rendered":"<p>Huhn mit Pflaumen f\u00fchrt uns in das Teheran der F\u00fcnfziger Jahre: Der Violinenvirtuose Nasser-Ali Khan hat ein gebrochenes Herz \u2013 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,19],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.official-trailer.com\/deutsch\/wp-json\/wp\/v2\/posts\/2869"}],"collection":[{"href":"https:\/\/www.official-trailer.com\/deutsch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.official-trailer.com\/deutsch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.official-trailer.com\/deutsch\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.official-trailer.com\/deutsch\/wp-json\/wp\/v2\/comments?post=2869"}],"version-history":[{"count":0,"href":"https:\/\/www.official-trailer.com\/deutsch\/wp-json\/wp\/v2\/posts\/2869\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.official-trailer.com\/deutsch\/wp-json\/wp\/v2\/media?parent=2869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.official-trailer.com\/deutsch\/wp-json\/wp\/v2\/categories?post=2869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.official-trailer.com\/deutsch\/wp-json\/wp\/v2\/tags?post=2869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}